{"id":240,"date":"2020-12-16T00:36:03","date_gmt":"2020-12-16T00:36:03","guid":{"rendered":"https:\/\/urologosenmerida.com.mx\/?page_id=240"},"modified":"2025-10-07T18:07:56","modified_gmt":"2025-10-07T18:07:56","slug":"home","status":"publish","type":"page","link":"https:\/\/urologosenmerida.com.mx\/","title":{"rendered":"Ur\u00f3logo en M\u00e9rida."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"240\" class=\"elementor elementor-240\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d9e782 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d9e782\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bcebbfe\" data-id=\"bcebbfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0d3513 elementor-widget elementor-widget-heading\" data-id=\"b0d3513\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Citas y urgencias <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji\" alt=\"\ud83d\udcde\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f4de.svg\"> 999 514 3165<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-431c491 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"431c491\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-649235a\" data-id=\"649235a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-469dc61 elementor-widget elementor-widget-image\" data-id=\"469dc61\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/urologosenmerida.com.mx\/index.php\/english\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"96\" height=\"22\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/04\/english.jpg\" class=\"attachment-large size-large wp-image-511\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4b9330 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4b9330\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1517e91\" data-id=\"1517e91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c57f03 elementor-widget elementor-widget-image\" data-id=\"2c57f03\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/11\/logo.jpg\" class=\"attachment-large size-large wp-image-123\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3f97b73\" data-id=\"3f97b73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ebdfc7 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"1ebdfc7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a6c90 elementor-widget elementor-widget-text-editor\" data-id=\"18a6c90\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<strong>Inicio\u00a0 \u00a0 \u00a0 \u00a0 <a href=\"#padecimientos\">Padecimientos<\/a>\u00a0 \u00a0 \u00a0 \u00a0 Procedimientos\u00a0 \u00a0 \u00a0 \u00a0 Turismo m\u00e9dico (ingl\u00e9s y espa\u00f1ol)<\/strong>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3421ba1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3421ba1\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc025aa\" data-id=\"bc025aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a47a4e6 elementor-widget elementor-widget-layerslider\" data-id=\"a47a4e6\" data-element_type=\"widget\" data-widget_type=\"layerslider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script type=\"text\/javascript\">jQuery(function() { _initLayerSlider( '#layerslider_3_1o1mtovavij6q', {createdWith: '6.11.2', sliderVersion: '6.11.2', type: 'fullwidth', allowFullscreen: false, skin: 'v6', showCircleTimer: false, skinsPath: 'https:\/\/urologosenmerida.com.mx\/wp-content\/plugins\/LayerSlider\/assets\/static\/layerslider\/skins\/'}); });<\/script><div id=\"layerslider_3_1o1mtovavij6q\" class=\"ls-wp-container fitvidsignore\" style=\"width:1000px;height:300px;margin:0 auto;margin-bottom: 0px;\"><div class=\"ls-slide\" data-ls=\"duration:3000;kenburnsscale:1.2;\"><img width=\"1536\" height=\"384\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/2.jpg\" class=\"ls-bg\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/2.jpg 1536w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/2-300x75.jpg 300w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/2-1024x256.jpg 1024w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/2-768x192.jpg 768w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/2-850x213.jpg 850w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><p style=\"top:152px;left:278px;background-size:inherit;background-position:inherit;font-size:35px;background-color:rgba(255, 255, 255, 0.86);\" class=\"ls-l\">Consulta + ultrasonido: $990<\/p><p style=\"top:102px;left:340px;background-size:inherit;background-position:inherit;font-size:35px;background-color:rgba(255, 255, 255, 0.86);\" class=\"ls-l\">Costo de consulta: $700<\/p><\/div><div class=\"ls-slide\" data-ls=\"duration:3000;kenburnsscale:1.2;\"><img width=\"1536\" height=\"384\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/3.jpg\" class=\"ls-bg\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/3.jpg 1536w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/3-300x75.jpg 300w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/3-1024x256.jpg 1024w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/3-768x192.jpg 768w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/3-850x213.jpg 850w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><p style=\"top:50%;left:50%;background-size:inherit;background-position:inherit;font-size:35px;background-color:rgba(255, 255, 255, 0.86);\" class=\"ls-l\">Cirug\u00eda laparosc\u00f3pica y rob\u00f3tica.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-068b910 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"068b910\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c36ea20\" data-id=\"c36ea20\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aab4fd8 elementor-widget elementor-widget-heading\" data-id=\"aab4fd8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Costo consulta: $900\n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7c8f6 elementor-widget elementor-widget-heading\" data-id=\"1f7c8f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Consulta + ultrasonido: $1,090<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4e574f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4e574f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ffccfc\" data-id=\"2ffccfc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-890a018 elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"890a018\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dabac0 elementor-widget elementor-widget-heading\" data-id=\"6dabac0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dr. Roberto Garc\u00eda<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19bc7ad elementor-widget elementor-widget-text-editor\" data-id=\"19bc7ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Ur\u00f3logo con alta especialidad en tratamientos de m\u00ednima invasi\u00f3n en c\u00e1ncer de pr\u00f3stata as\u00ed como c\u00e1ncer de ri\u00f1\u00f3n y veijga tanto en hombres como mujeres a trav\u00e9s de la cirug\u00eda laparosc\u00f3pica y rob\u00f3tica<\/p><p>Experto en cirug\u00eda de m\u00ednima invasi\u00f3n tanto endosc\u00f3pica, percut\u00e1nea, laparosc\u00f3pica y rob\u00f3tica.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b47d7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b0b47d7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?phone=5219992790201&#038;text=Hola,%20vi%20su%20p%C3%A1gina%20web%20y%20me%20gustar%C3%ADa%20agendar%20una%20cita\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar cita<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c38739\" data-id=\"1c38739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4665f87 elementor-widget elementor-widget-image\" data-id=\"4665f87\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"530\" height=\"530\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2024\/04\/Roberto-Garcia-Carrillo.png\" class=\"attachment-large size-large wp-image-630\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2024\/04\/Roberto-Garcia-Carrillo.png 530w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2024\/04\/Roberto-Garcia-Carrillo-300x300.png 300w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2024\/04\/Roberto-Garcia-Carrillo-150x150.png 150w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78b58ad elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78b58ad\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-865dd8d\" data-id=\"865dd8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06ea80b elementor-widget elementor-widget-heading\" data-id=\"06ea80b\" data-element_type=\"widget\" id=\"padecimientos\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PADECIMIENTOS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7e4bf0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7e4bf0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0657cf7\" data-id=\"0657cf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d25dec4 elementor-widget elementor-widget-text-editor\" data-id=\"d25dec4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-320 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Ca\u0301ncer-de-pro\u0301stata-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9a736af\" data-id=\"9a736af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-328a06e elementor-widget elementor-widget-text-editor\" data-id=\"328a06e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-323 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Ca\u0301ncer_renal-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-78a8dfc\" data-id=\"78a8dfc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03618bc elementor-widget elementor-widget-text-editor\" data-id=\"03618bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-328 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Crecimiento-de-pro\u0301stata-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cafe7e9 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cafe7e9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ceab218\" data-id=\"ceab218\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5322771 elementor-widget elementor-widget-text-editor\" data-id=\"5322771\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-331 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Ca\u0301lculo-renal-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9a654f3\" data-id=\"9a654f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39939a1 elementor-widget elementor-widget-text-editor\" data-id=\"39939a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-334 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Infeccio\u0301n-vi\u0301as-urinarias-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-245ea8e\" data-id=\"245ea8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b45b201 elementor-widget elementor-widget-text-editor\" data-id=\"b45b201\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-337 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Fimosis-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df50712 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df50712\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b3d10be\" data-id=\"b3d10be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01e24e2 elementor-widget elementor-widget-text-editor\" data-id=\"01e24e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-340 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/Cirugi\u0301a-laparosco\u0301pica-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f94cef2\" data-id=\"f94cef2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-684a250 elementor-widget elementor-widget-text-editor\" data-id=\"684a250\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\"><div class=\"popupaoc-shortcode-preview\">\r\n\t<div class=\"paoc-image-popup\">\r\n\t\t<a class=\"paoc-popup-click paoc-popup-cust-343 paoc-popup-image paoc-popup-image\" href=\"javascript:void(0);\"><img decoding=\"async\" class=\"popupaoc-img\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/12\/cirugia-robotica-300x205.jpg\" alt=\"\" \/><\/a>\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div><\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca249fc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca249fc\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da46b31\" data-id=\"da46b31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2776f5 elementor-widget elementor-widget-heading\" data-id=\"d2776f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 elegir CIERA?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-619d800 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"619d800\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c5dc207\" data-id=\"c5dc207\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b94a3a elementor-widget elementor-widget-pp-flipbox\" data-id=\"9b94a3a\" data-element_type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-left\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-md\"><\/i>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tUr\u00f3logo con alta especialidad\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-flipbox-icon-image-back pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tUr\u00f3logo con alta especialidad en tratamientos de m\u00ednima invasi\u00f3n en c\u00e1ncer de pr\u00f3stata as\u00ed como c\u00e1ncer de ri\u00f1\u00f3n y veijga tanto en hombres como mujeres a trav\u00e9s de la cirug\u00eda laparosc\u00f3pica y rob\u00f3tica. Ofrecemos tratamiento avanzado para c\u00e1lculos de ri\u00f1\u00f3n y vejiga tanto en hombres como mujeres.  \t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ae651b\" data-id=\"7ae651b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb51463 elementor-widget elementor-widget-pp-flipbox\" data-id=\"eb51463\" data-element_type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-left\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-award\"><\/i>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tUr\u00f3logo certificado\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-flipbox-icon-image-back pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tUr\u00f3logo certificado ante el Consejo Nacional Mexicano de Urolog\u00eda as\u00ed como certificaci\u00f3n en cirug\u00eda rob\u00f3tica Estados Unidos en cirug\u00eda rob\u00f3tica, investigaci\u00f3n en c\u00e1ncer de pr\u00f3stata en Colegio Imperial de Londres, entrenamiento en cirug\u00eda laparosc\u00f3pica en c\u00e1ncer de ri\u00f1\u00f3n y pr\u00f3stata y entrenamiento en cirug\u00eda rob\u00f3tica en Francia. \nPosgrados en las siguientes instituciones:\n- Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM)\n- Instituto Polit\u00e9cnico Nacional (IPN)\n- Instituto Tecnol\u00f3gico de Estudios Superiores de Monterrey (Tec de Monterrey)\n- Instituto de Estudios Superiores en Administraci\u00f3n P\u00fablica\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8945706\" data-id=\"8945706\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ceb042e elementor-widget elementor-widget-pp-flipbox\" data-id=\"ceb042e\" data-element_type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-left\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-microscope\"><\/i>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tTecnolog\u00eda de punta\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-flipbox-icon-image-back pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tExperto en cirug\u00eda de m\u00ednima invasi\u00f3n tanto endosc\u00f3pica, percut\u00e1nea, laparosc\u00f3pica y rob\u00f3tica. \t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af5348b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af5348b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ff0af9\" data-id=\"6ff0af9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a78dd3 elementor-widget elementor-widget-image\" data-id=\"5a78dd3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"336\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/Capture-768x403.png\" class=\"attachment-medium_large size-medium_large wp-image-429\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/Capture-768x403.png 768w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/Capture-300x157.png 300w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/Capture-1024x537.png 1024w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/Capture-850x446.png 850w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2021\/01\/Capture.png 1091w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4ceef0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4ceef0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b19ffc\" data-id=\"3b19ffc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a2d2d6 elementor-widget elementor-widget-spacer\" data-id=\"2a2d2d6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65ebac1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65ebac1\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98a3345\" data-id=\"98a3345\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06ee5cf elementor-widget elementor-widget-heading\" data-id=\"06ee5cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Zona Pensiones<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d42659d elementor-widget elementor-widget-text-editor\" data-id=\"d42659d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Calle 32 #198 x 17 y 21 Col. Garc\u00eda Giner\u00e9s. A 100 metros del hospital Ju\u00e1rez.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81cf537 elementor-widget elementor-widget-google_maps\" data-id=\"81cf537\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=20.99037742614746%2C-89.63844299316406&#038;t=m&#038;z=17&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"20.99037742614746,-89.63844299316406\"\n\t\t\t\t\taria-label=\"20.99037742614746,-89.63844299316406\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aab7954 elementor-widget elementor-widget-text-editor\" data-id=\"aab7954\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Teclea aqu\u00ed...\">Citas <img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f4de.svg\" alt=\"\ud83d\udcde\" \/> 999 514 3165<\/h4>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6b914a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6b914a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fe4555\" data-id=\"7fe4555\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9005b49 elementor-widget elementor-widget-image\" data-id=\"9005b49\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/05\/CreadoPorDrInn-300x100.png\" class=\"attachment-medium size-medium wp-image-37\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/05\/CreadoPorDrInn-300x100.png 300w, https:\/\/urologosenmerida.com.mx\/wp-content\/uploads\/2020\/05\/CreadoPorDrInn.png 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52dd62c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52dd62c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e646ef\" data-id=\"3e646ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3d7c2 elementor-widget elementor-widget-text-editor\" data-id=\"4f3d7c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<a style=\"color: #e4e4e4;\" href=\"https:\/\/urologosenmerida.com.mx\/aviso-de-privacidad\/\">Aviso de Privacidad<\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c2b6955\" data-id=\"c2b6955\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f37ab4a elementor-widget elementor-widget-text-editor\" data-id=\"f37ab4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>COFEPRIS 213301202A0698<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Citas y urgencias 999 514 3165 Inicio\u00a0 \u00a0 \u00a0 \u00a0 Padecimientos\u00a0 \u00a0 \u00a0 \u00a0 Procedimientos\u00a0 \u00a0 \u00a0 \u00a0 Turismo m\u00e9dico (ingl\u00e9s y espa\u00f1ol) Consulta + ultrasonido: $990 Costo de consulta: $700 Cirug\u00eda laparosc\u00f3pica y rob\u00f3tica. Costo consulta: $900 Consulta + ultrasonido: $1,090 Dr. Roberto Garc\u00eda Ur\u00f3logo con alta especialidad en tratamientos de m\u00ednima invasi\u00f3n en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":[],"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ur\u00f3logo en M\u00e9rida. -<\/title>\n<meta name=\"description\" content=\"Ur\u00f3logo en M\u00e9rida experto en tratamiento de pr\u00f3stata y c\u00e1lculos. Certificado ante consejo y alta especialidad UNAM.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urologosenmerida.com.mx\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ur\u00f3logo en M\u00e9rida. -\" \/>\n<meta property=\"og:description\" content=\"Ur\u00f3logo en M\u00e9rida experto en tratamiento de pr\u00f3stata y c\u00e1lculos. Certificado ante consejo y alta especialidad UNAM.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urologosenmerida.com.mx\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T18:07:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f4de.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/urologosenmerida.com.mx\/\",\"url\":\"https:\/\/urologosenmerida.com.mx\/\",\"name\":\"Ur\u00f3logo en M\u00e9rida. -\",\"isPartOf\":{\"@id\":\"https:\/\/urologosenmerida.com.mx\/#website\"},\"datePublished\":\"2020-12-16T00:36:03+00:00\",\"dateModified\":\"2025-10-07T18:07:56+00:00\",\"description\":\"Ur\u00f3logo en M\u00e9rida experto en tratamiento de pr\u00f3stata y c\u00e1lculos. Certificado ante consejo y alta especialidad UNAM.\",\"breadcrumb\":{\"@id\":\"https:\/\/urologosenmerida.com.mx\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/urologosenmerida.com.mx\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/urologosenmerida.com.mx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/urologosenmerida.com.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ur\u00f3logo en M\u00e9rida.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/urologosenmerida.com.mx\/#website\",\"url\":\"https:\/\/urologosenmerida.com.mx\/\",\"name\":\"\",\"description\":\"Ur\u00f3logo en M\u00e9rida certificado y con alta especialidad y certificado por el consejo Mexicano de Urolog\u00eda. Atenci\u00f3n especializadas en padecimientos como crecimiento y c\u00e1ncer de pr\u00f3stata, c\u00e1lculos renales as\u00ed como VPH y padecimientos en genitales.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/urologosenmerida.com.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ur\u00f3logo en M\u00e9rida. -","description":"Ur\u00f3logo en M\u00e9rida experto en tratamiento de pr\u00f3stata y c\u00e1lculos. Certificado ante consejo y alta especialidad UNAM.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urologosenmerida.com.mx\/","og_locale":"es_MX","og_type":"article","og_title":"Ur\u00f3logo en M\u00e9rida. -","og_description":"Ur\u00f3logo en M\u00e9rida experto en tratamiento de pr\u00f3stata y c\u00e1lculos. Certificado ante consejo y alta especialidad UNAM.","og_url":"https:\/\/urologosenmerida.com.mx\/","article_modified_time":"2025-10-07T18:07:56+00:00","og_image":[{"url":"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f4de.svg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/urologosenmerida.com.mx\/","url":"https:\/\/urologosenmerida.com.mx\/","name":"Ur\u00f3logo en M\u00e9rida. -","isPartOf":{"@id":"https:\/\/urologosenmerida.com.mx\/#website"},"datePublished":"2020-12-16T00:36:03+00:00","dateModified":"2025-10-07T18:07:56+00:00","description":"Ur\u00f3logo en M\u00e9rida experto en tratamiento de pr\u00f3stata y c\u00e1lculos. Certificado ante consejo y alta especialidad UNAM.","breadcrumb":{"@id":"https:\/\/urologosenmerida.com.mx\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/urologosenmerida.com.mx\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/urologosenmerida.com.mx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/urologosenmerida.com.mx\/"},{"@type":"ListItem","position":2,"name":"Ur\u00f3logo en M\u00e9rida."}]},{"@type":"WebSite","@id":"https:\/\/urologosenmerida.com.mx\/#website","url":"https:\/\/urologosenmerida.com.mx\/","name":"","description":"Ur\u00f3logo en M\u00e9rida certificado y con alta especialidad y certificado por el consejo Mexicano de Urolog\u00eda. Atenci\u00f3n especializadas en padecimientos como crecimiento y c\u00e1ncer de pr\u00f3stata, c\u00e1lculos renales as\u00ed como VPH y padecimientos en genitales.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urologosenmerida.com.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"}]}},"_links":{"self":[{"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/240"}],"collection":[{"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=240"}],"version-history":[{"count":211,"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/240\/revisions"}],"predecessor-version":[{"id":735,"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/240\/revisions\/735"}],"wp:attachment":[{"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urologosenmerida.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}